{"id":8202,"date":"2015-01-27T14:35:59","date_gmt":"2015-01-27T12:35:59","guid":{"rendered":"http:\/\/www.eoc.ee\/?p=8202"},"modified":"2015-01-27T14:35:59","modified_gmt":"2015-01-27T12:35:59","slug":"visite-du-patriarche-oecumenique-en-estonie-en-2013-7","status":"publish","type":"post","link":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/","title":{"rendered":"Visite du patriarche oecumenique en Estonie en 2013 &#8211; 7"},"content":{"rendered":"<p>EGLISE ORTHODOXE D\u2019ESTONIE<br \/>\nVISITE DU PATRIARCHE OECUMENIQUE<br \/>\n(4 au 11 septembre 2013)<\/p>\n<p>&nbsp;<\/p>\n<p><b>Kuressaare, \u00eele de Saaremaa (Estonie) <\/b><br \/>\n<b>Lundi 9 septembre 2013 (soir)<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\">90<sup>\u00e8me<\/sup> anniversaire de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie\u00a0: Le Patriarche \u0153cum\u00e9nique de Constantinople rencontre les acteurs de la soci\u00e9t\u00e9 civile des \u00eeles de la Baltique. <\/span><\/p>\n<p>Le Patriarche \u0153cum\u00e9nique de Constantinople Bartholom\u00e9e c\u00e9l\u00e8bre en Estonie le 90<sup>\u00e8me<\/sup> anniversaire de la proclamation de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie, du 4 au 11 septembre 2013. Lundi soir 9 septembre, il a rencontr\u00e9 les forces vives de l\u2019\u00eele de Saaremaa (1\/5 de la superficie de l\u2019Estonie) lors d\u2019un d\u00eener offert par le gouverneur de l\u2019\u00eele, en pr\u00e9sence de l\u2019ancien Pr\u00e9sident de la R\u00e9publique, M. Arnold R\u00dc\u00dcTEL.<\/p>\n<p>Depuis son arriv\u00e9e \u00e0 Tallinn mercredi 4 septembre 2013, les Estoniens ont appris \u00e0 r\u00e9gler leur pas sur celui du Patriarche Bartholom\u00e9e, pas qu\u2019il a rapide et assur\u00e9. C\u2019est donc \u00e0 pieds qu\u2019il est arriv\u00e9 au Casino de Kuressaare, accueilli par M. Kaido KAASIK et une centaine de convives fiers de cette premi\u00e8re visite d\u2019un Patriarche \u0153cum\u00e9nique dans le Pays de Saare. \u00ab\u00a0Le 90<sup>\u00e8me<\/sup> anniversaire de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie est un \u00e9v\u00e9nement important pour tout le peuple\u00a0\u00bb lui a dit le Gouverneur, \u00ab\u00a0en particulier celui de notre \u00eele o\u00f9 la soci\u00e9t\u00e9 a \u00e9volu\u00e9, o\u00f9 la vie quotidienne a consid\u00e9rablement chang\u00e9, o\u00f9 les communaut\u00e9s chr\u00e9tiennes ont appris \u00e0 dialoguer. Nous savons aussi que, comme nous, vous \u00eates sensible \u00e0 l\u2019\u00e9quilibre \u00e9cologique de la nature et \u00e0 la protection de l\u2019environnement. Notre joie de vous recevoir ici est donc r\u00e9elle et pas seulement de convenance.\u00a0\u00bb<\/p>\n<p>Dans sa r\u00e9ponse, le Patriarche \u0153cum\u00e9nique de Constantinople a expliqu\u00e9 que, c\u00e9l\u00e9brant en Estonie le 90<sup>\u00e8me<\/sup> anniversaire de l\u2019Eglise orthodoxe, \u00ab\u00a0il ne pouvait pas ne pas venir \u00e0 Saaremaa pour admirer une nature dot\u00e9e par Dieu de tant de richesses et de beaut\u00e9s, dans un\u00a0 environnement naturel extraordinaire\u00a0\u00bb. Bartholom\u00e9e a salu\u00e9 \u00e9galement le courage des habitants durant l\u2019annexion sovi\u00e9tique\u00a0: \u00ab\u00a0La pr\u00e9sence chr\u00e9tienne orthodoxe est rest\u00e9e vivante en d\u00e9pit de toutes les difficult\u00e9s rencontr\u00e9es. Cela prouve que vous \u00eates des hommes et des femmes dynamiques et entreprenants, \u00e0 l\u2019image des fid\u00e8les des paroisses orthodoxes de cette \u00eele de Saaremaa qui sont tr\u00e8s actifs dans la soci\u00e9t\u00e9 civile, ce que nous encourageons vivement.\u00a0\u00bb<\/p>\n<p>Pour le remercier de son accueil, le Patriarche Bartholom\u00e9e a offert au Gouverneur une croix de l\u2019\u00eele de Pathmos, pour qu\u2019elle le prot\u00e9ge, lui et sa famille et lui rappelle l\u2019heureux moment de cette soir\u00e9e. Demain, jeudi 10 septembre 2013, le Patriarche et sa d\u00e9l\u00e9gation visiteront le M\u00e9morial qui retrace les ann\u00e9es noires des occupations allemandes et russes, de 1939 \u00e0 1991.<\/p>\n<p>&nbsp;<\/p>\n<p>A Kuressaare, sur l\u2019\u00eele de Saaremaa (Estonie), Jean-Fran\u00e7ois JOLIVALT, pour EA\u00d5K<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EGLISE ORTHODOXE D\u2019ESTONIE VISITE DU PATRIARCHE OECUMENIQUE (4 au 11 septembre 2013) &nbsp; Kuressaare, \u00eele de Saaremaa (Estonie) Lundi 9 septembre 2013 (soir) &nbsp; 90\u00e8me anniversaire de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie\u00a0: Le Patriarche \u0153cum\u00e9nique de Constantinople rencontre les acteurs de la soci\u00e9t\u00e9 civile des \u00eeles de la Baltique. Le Patriarche \u0153cum\u00e9nique de Constantinople Bartholom\u00e9e [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[120,169],"tags":[156,128,127,155],"class_list":["post-8202","post","type-post","status-publish","format-standard","hentry","category-histoire","category-theologie-orthodoxe","tag-constantinople","tag-estonie","tag-metropolite-2","tag-patriarcat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d&#039;Estonie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d&#039;Estonie\" \/>\n<meta property=\"og:description\" content=\"EGLISE ORTHODOXE D\u2019ESTONIE VISITE DU PATRIARCHE OECUMENIQUE (4 au 11 septembre 2013) &nbsp; Kuressaare, \u00eele de Saaremaa (Estonie) Lundi 9 septembre 2013 (soir) &nbsp; 90\u00e8me anniversaire de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie\u00a0: Le Patriarche \u0153cum\u00e9nique de Constantinople rencontre les acteurs de la soci\u00e9t\u00e9 civile des \u00eeles de la Baltique. Le Patriarche \u0153cum\u00e9nique de Constantinople Bartholom\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Orthodoxe d&#039;Estonie\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-27T12:35:59+00:00\" \/>\n<meta name=\"author\" content=\"Heike H\u00e4rma\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heike H\u00e4rma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/\"},\"author\":{\"name\":\"Heike H\u00e4rma\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/#\\\/schema\\\/person\\\/bfa03b2406703aa1a9256392aaa001b3\"},\"headline\":\"Visite du patriarche oecumenique en Estonie en 2013 &#8211; 7\",\"datePublished\":\"2015-01-27T12:35:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/\"},\"wordCount\":507,\"keywords\":[\"Constantinople\",\"Estonie\",\"m\u00e9tropolite\",\"patriarcat\"],\"articleSection\":[\"Histoire\",\"Th\u00e9ologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/\",\"url\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/\",\"name\":\"Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d'Estonie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/#website\"},\"datePublished\":\"2015-01-27T12:35:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/#\\\/schema\\\/person\\\/bfa03b2406703aa1a9256392aaa001b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/histoire\\\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eoc.ee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visite du patriarche oecumenique en Estonie en 2013 &#8211; 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.eoc.ee\\\/\",\"name\":\"\u00c9glise Orthodoxe d'Estonie\",\"description\":\"Eesti Apostlik-\u00d5igeusu Kirik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eoc.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eoc.ee\\\/#\\\/schema\\\/person\\\/bfa03b2406703aa1a9256392aaa001b3\",\"name\":\"Heike H\u00e4rma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g\",\"caption\":\"Heike H\u00e4rma\"},\"url\":\"https:\\\/\\\/www.eoc.ee\\\/fr\\\/author\\\/heike\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d'Estonie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/","og_locale":"fr_FR","og_type":"article","og_title":"Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d'Estonie","og_description":"EGLISE ORTHODOXE D\u2019ESTONIE VISITE DU PATRIARCHE OECUMENIQUE (4 au 11 septembre 2013) &nbsp; Kuressaare, \u00eele de Saaremaa (Estonie) Lundi 9 septembre 2013 (soir) &nbsp; 90\u00e8me anniversaire de l\u2019autonomie de l\u2019Eglise orthodoxe d\u2019Estonie\u00a0: Le Patriarche \u0153cum\u00e9nique de Constantinople rencontre les acteurs de la soci\u00e9t\u00e9 civile des \u00eeles de la Baltique. Le Patriarche \u0153cum\u00e9nique de Constantinople Bartholom\u00e9e [&hellip;]","og_url":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/","og_site_name":"\u00c9glise Orthodoxe d'Estonie","article_published_time":"2015-01-27T12:35:59+00:00","author":"Heike H\u00e4rma","twitter_misc":{"\u00c9crit par":"Heike H\u00e4rma","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/#article","isPartOf":{"@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/"},"author":{"name":"Heike H\u00e4rma","@id":"https:\/\/www.eoc.ee\/#\/schema\/person\/bfa03b2406703aa1a9256392aaa001b3"},"headline":"Visite du patriarche oecumenique en Estonie en 2013 &#8211; 7","datePublished":"2015-01-27T12:35:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/"},"wordCount":507,"keywords":["Constantinople","Estonie","m\u00e9tropolite","patriarcat"],"articleSection":["Histoire","Th\u00e9ologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/","url":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/","name":"Visite du patriarche oecumenique en Estonie en 2013 - 7 &#8211; \u00c9glise Orthodoxe d'Estonie","isPartOf":{"@id":"https:\/\/www.eoc.ee\/#website"},"datePublished":"2015-01-27T12:35:59+00:00","author":{"@id":"https:\/\/www.eoc.ee\/#\/schema\/person\/bfa03b2406703aa1a9256392aaa001b3"},"breadcrumb":{"@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eoc.ee\/fr\/histoire\/visite-du-patriarche-oecumenique-en-estonie-en-2013-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eoc.ee\/"},{"@type":"ListItem","position":2,"name":"Visite du patriarche oecumenique en Estonie en 2013 &#8211; 7"}]},{"@type":"WebSite","@id":"https:\/\/www.eoc.ee\/#website","url":"https:\/\/www.eoc.ee\/","name":"\u00c9glise Orthodoxe d'Estonie","description":"Eesti Apostlik-\u00d5igeusu Kirik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eoc.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.eoc.ee\/#\/schema\/person\/bfa03b2406703aa1a9256392aaa001b3","name":"Heike H\u00e4rma","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8eb3cb357606a6c8ed98d4b92714824fc7d2f06e57b58d2b730a00e0199effb6?s=96&d=mm&r=g","caption":"Heike H\u00e4rma"},"url":"https:\/\/www.eoc.ee\/fr\/author\/heike\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/posts\/8202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/comments?post=8202"}],"version-history":[{"count":1,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/posts\/8202\/revisions"}],"predecessor-version":[{"id":8203,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/posts\/8202\/revisions\/8203"}],"wp:attachment":[{"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/media?parent=8202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/categories?post=8202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eoc.ee\/fr\/wp-json\/wp\/v2\/tags?post=8202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}